{"id":11,"count":1,"description":"","link":"https:\/\/disorder.dk\/wonderware\/tag\/master\/","name":"Master","slug":"master","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/disorder.dk\/wonderware\/wp-json\/wp\/v2\/tags\/11","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/disorder.dk\/wonderware\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/disorder.dk\/wonderware\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/disorder.dk\/wonderware\/wp-json\/wp\/v2\/posts?tags=11"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}